{"id":27541,"date":"2023-01-16T11:17:31","date_gmt":"2023-01-16T10:17:31","guid":{"rendered":"https:\/\/www.stelorder.com\/blog\/gestion-jornada-intensiva\/"},"modified":"2024-01-11T09:40:07","modified_gmt":"2024-01-11T08:40:07","slug":"gestion-jornada-intensiva","status":"publish","type":"post","link":"https:\/\/www.stelorder.com\/fr\/blog\/gestion-jornada-intensiva\/","title":{"rendered":"Gesti\u00f3n de jornada intensiva"},"content":{"rendered":"\n<p>Cada vez son m\u00e1s las empresas que se animan a implantar el horario intensivo durante una determinada \u00e9poca del a\u00f1o (generalmente en verano) o algunos d\u00edas de la semana (habitualmente los viernes). Algunas incluso est\u00e1n probando ya a implantar esta jornada de forma permanente.<\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_82_2 counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\"><p class=\"ez-toc-title\" style=\"cursor:inherit\">Sommaire<\/p>\n<\/div><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.stelorder.com\/fr\/blog\/gestion-jornada-intensiva\/#que-es-la-jornada-intensiva\" >Qu\u00e9 es la jornada intensiva<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.stelorder.com\/fr\/blog\/gestion-jornada-intensiva\/#regulacion-de-la-jornada-de-trabajo-intensiva\" >Regulaci\u00f3n de la jornada de trabajo intensiva<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.stelorder.com\/fr\/blog\/gestion-jornada-intensiva\/#cuantas-horas-se-trabaja-durante-la-jornada-intensiva-de-verano-y-de-viernes\" >Cu\u00e1ntas horas se trabaja durante la jornada intensiva de verano y de viernes<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.stelorder.com\/fr\/blog\/gestion-jornada-intensiva\/#como-implementar-la-jornada-intensiva-en-tu-empresa\" >C\u00f3mo implementar la jornada intensiva en tu empresa<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.stelorder.com\/fr\/blog\/gestion-jornada-intensiva\/#beneficios-y-desventajas-de-la-jornada-intensiva\" >Beneficios y desventajas de la jornada intensiva<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"que-es-la-jornada-intensiva\"><\/span><strong>Qu\u00e9 es la jornada intensiva<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Es jornada continua aquella que se lleva a cabo&nbsp;<strong>sin pausas o interrupciones<\/strong>, m\u00e1s all\u00e1 de los 15 minutos de descanso que el Estatuto de los Trabajadores recoge como obligatorios cuando el tiempo de trabajo excede de seis horas seguidas.<\/p>\n\n\n\n<p>Se trata justo de lo contrario a la jornada partida, que suele ser la habitual en Espa\u00f1a, en la que se realiza una pausa m\u00e1s o menos larga a la hora comer, lo que provoca que el horario de salida del trabajo se retrase.<\/p>\n\n\n\n<p><strong>Uno de los grandes problemas para la conciliaci\u00f3n es que las jornadas laborales se alargan m\u00e1s de lo necesario<\/strong>. Los empleados trabajan de media ocho horas al d\u00eda, pero en realidad, pasan mucho m\u00e1s tiempo en su lugar de trabajo, porque la mayor\u00eda de ellos no pueden aprovechar para irse a casa en el rato de la comida.<\/p>\n\n\n\n<p>As\u00ed, podemos encontrarnos con personas que entran a trabajar a las 8 de la ma\u00f1ana y, sin embargo, no abandonan la oficina hasta las 18 horas. Esto ocurre porque lo habitual es que entre la ma\u00f1ana y la tarde haya un descanso de hora y media o dos horas para comer. Si a esto le sumamos el tiempo que hay que invertir en el desplazamiento de casa al trabajo, y viceversa,&nbsp;<strong>muchos trabajadores pasan m\u00e1s de 12 horas al d\u00eda fuera de casa<\/strong>, lo que hace imposible la conciliaci\u00f3n.<\/p>\n\n\n\n<p>Frente a este problema,&nbsp;<strong>la jornada laboral intensiva se perfila como la soluci\u00f3n m\u00e1s id\u00f3nea<\/strong>. Al eliminar el tiempo de la comida, los empleados pueden irse a su casa mucho antes.&nbsp;<strong>No supone trabajar menos, sino hacer una gesti\u00f3n m\u00e1s eficiente del tiempo.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"regulacion-de-la-jornada-de-trabajo-intensiva\"><\/span><strong>Regulaci\u00f3n de la jornada de trabajo intensiva<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>El Estatuto de los Trabajadores no hace una menci\u00f3n expresa a este tipo de jornada de trabajo, por lo que para conocer su regulaci\u00f3n hay que acudir al&nbsp;<strong>convenio colectivo que resulte de aplicaci\u00f3n en cada caso concreto<\/strong>. Si esta norma fruto de la negociaci\u00f3n colectiva tampoco dice nada sobre el tema, se atender\u00e1 a la&nbsp;<strong>pol\u00edtica interna de cada empresa<\/strong>.<\/p>\n\n\n\n<p>Mientras no se exceda la jornada m\u00e1xima anual fijada legalmente, no suele haber mayor problema para que cada empresa organice el tiempo de trabajo en la misma de la forma que considere m\u00e1s adecuada. Eso s\u00ed, con independencia del tipo de jornada aplicada, la obligaci\u00f3n de realizar el&nbsp;<a href=\"https:\/\/www.stelorder.com\/blog\/control-horario\/\" target=\"_blank\" rel=\"noreferrer noopener\">control horario del tiempo de trabajo<\/a>&nbsp;siempre existe.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"cuantas-horas-se-trabaja-durante-la-jornada-intensiva-de-verano-y-de-viernes\"><\/span><strong>Cu\u00e1ntas horas se trabaja durante la jornada intensiva de verano y de viernes<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>En empresas o sectores que aplican la<strong>&nbsp;jornada intensiva durante todo el a\u00f1o<\/strong>, el tiempo de trabajo suele estar dividido en&nbsp;<strong>jornadas de 8 horas diarias<\/strong>&nbsp;que pueden hacerse en turnos de ma\u00f1ana, tarde o noche, incluso en turnos rotativos.<\/p>\n\n\n\n<p>En el caso de compa\u00f1\u00edas en las que este tipo de jornada&nbsp;<strong>solo se aplica los viernes, o durante el per\u00edodo estival, lo que se hace es una compensaci\u00f3n de horas<\/strong>. Por ejemplo, durante la jornada intensiva de verano se trabajan menos horas (lo habitual es hacer siete horas al d\u00eda en lugar de ocho), y esa hora de trabajo que se pierde cada d\u00eda se compensa al volver al horario de invierno.<\/p>\n\n\n\n<p>En las empresas que aplican la jornada intensiva solo los viernes, lo habitual es que el \u00faltimo d\u00eda de la semana se trabaje un poco menos y de lunes a jueves se trabaje un poco m\u00e1s de tiempo para compensar.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"como-implementar-la-jornada-intensiva-en-tu-empresa\"><\/span><strong>C\u00f3mo implementar la jornada intensiva en tu empresa<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Aunque el convenio colectivo que se aplica en tu sector de actividad no diga nada al respecto, puedes implantar la jornada continua en tu empresa. Puedes establecer una jornada de este tipo para todo el a\u00f1o, solo los viernes, o \u00fanicamente durante el verano.<\/p>\n\n\n\n<p>Lo recomendable en estos casos es que inicies un<strong>&nbsp;di\u00e1logo con los representantes de los trabajadores&nbsp;<\/strong>para conocer el sentir de la plantilla con respecto a un ajuste en su horario. Aunque te aseguramos que, en la mayor\u00eda de los casos, este cambio suele ser bien aceptado.<\/p>\n\n\n\n<p>Si la idea es bien recibida, lo siguiente que hay que hacer es&nbsp;<strong>fijar el nuevo horario<\/strong>. En Espa\u00f1a, la jornada intensiva se aplica especialmente en los turnos de ma\u00f1ana, y&nbsp;<strong>lo m\u00e1s com\u00fan es trabajar de 8:00 a 16:00 o de 7:00 a 15:00 horas.<\/strong>&nbsp;Algunas empresas incluso distinguen entre el horario de verano y el de invierno. De esta forma, en invierno trabajan de 8:00 a 16:00 horas y en verano de 7:00 a 15:00 horas. En cualquier caso, como hemos se\u00f1alado antes,<strong>&nbsp;contin\u00faa siendo obligatorio hacer un control horario&nbsp;<\/strong>para que la Autoridad Laboral pueda comprobar que no se est\u00e1n trabajando horas de m\u00e1s, as\u00ed que conviene determinar qu\u00e9&nbsp;<a href=\"https:\/\/www.stelorder.com\/blog\/aplicaciones-fichar-trabajo\/\" target=\"_blank\" data-type=\"post\" data-id=\"18480\" rel=\"noreferrer noopener\">aplicaciones para fichar en el trabajo<\/a>&nbsp;se van a emplear.<\/p>\n\n\n\n<p>En jornadas continuadas no hay una pausa para comer, y es eso precisamente lo que permite que los empleados salgan antes, pero eso no quiere decir que no haya descanso. El Estatuto de los Trabajadores establece que, en las jornadas sin pausa de m\u00e1s de seis horas de duraci\u00f3n, los&nbsp;<strong>empleados tienen derecho a un descanso de 15 minutos<\/strong>. As\u00ed que vas a tener que establecer la forma en que se va a disfrutar de este descanso, para que todo el mundo acceda a \u00e9l, pero no lo hagan todos los empleados al mismo tiempo.&nbsp;<strong>Lo habitual es reconocer ese lapso como tiempo efectivo de trabajo<\/strong>. Es decir, que los trabajadores no tienen que recuperarlo despu\u00e9s.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u00bfQu\u00e9 ocurre con los trabajadores a tiempo parcial?<\/strong><\/h3>\n\n\n\n<p>La jornada intensiva est\u00e1 pensada para aquellos que tienen un contrato a jornada completa. Si en tu empresa hay empleados contratados a tiempo parcial,<strong>&nbsp;el paso a un sistema de trabajo continuado no implica necesariamente que deban trabajar menos horas<\/strong>. La clave est\u00e1 en ajustar su tiempo de trabajo dentro del nuevo horario.<\/p>\n\n\n\n<p>Por ejemplo, si el horario de tu empresa ha pasado a ser de 7:00 a 15:00 horas, los empleados con contrato a tiempo parcial pueden trabajar de 7:00 a 11:00 o de 11:00 a 15:00 horas.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u00bfY si tienes aut\u00f3nomos trabajando en tu negocio?<\/strong><\/h3>\n\n\n\n<p>Supongamos que tienes algunas de las tareas externalizadas y cuentas con uno o varios aut\u00f3nomos que desempe\u00f1an estas labores desde tus instalaciones. Estos&nbsp;<strong>tienen la opci\u00f3n de negarse al nuevo horario de trabajo<\/strong>, ya que tienen derecho a gestionar su tiempo de trabajo con total libertad. No obstante, lo m\u00e1s probable es que estos profesionales no tengan ning\u00fan inconveniente para ajustar su tiempo de trabajo, y estar\u00e1n m\u00e1s que dispuestos a renunciar a la pausa de la comida si, a cambio, pueden irse a casa unas horas antes.<\/p>\n\n\n\n<figure class=\"gb-block-image gb-block-image-0988b1a3\"><img decoding=\"async\" width=\"800\" height=\"533\" class=\"gb-image gb-image-0988b1a3\" src=\"https:\/\/www.stelorder.com\/wp-content\/uploads\/2024\/01\/blog-jornada-intensiva.png\" alt=\"Explica una persona a otra como funciona la jornada intensiva.\" title=\"blog-jornada-intensiva\" srcset=\"https:\/\/www.stelorder.com\/wp-content\/uploads\/2024\/01\/blog-jornada-intensiva.png 800w, https:\/\/www.stelorder.com\/wp-content\/uploads\/2024\/01\/blog-jornada-intensiva-300x200.png 300w, https:\/\/www.stelorder.com\/wp-content\/uploads\/2024\/01\/blog-jornada-intensiva-768x512.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\n<figcaption class=\"gb-headline gb-headline-354886ca gb-headline-text\">Dos trabajadoras discutiendo sobre la jornada intensiva.<\/figcaption>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"beneficios-y-desventajas-de-la-jornada-intensiva\"><\/span><strong>Beneficios y desventajas de la jornada intensiva<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Beneficios<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Mejora la conciliaci\u00f3n<\/strong>. Permite que los empleados tengan m\u00e1s tiempo libre cada d\u00eda, lo que les permite compatibilizar mejor su trabajo con su vida personal, atendiendo a sus responsabilidades familiares, o disfrutando del ocio.<\/li>\n\n\n\n<li><strong>Reduce el estr\u00e9s<\/strong>. Al no tener que pasar gran parte de su d\u00eda a d\u00eda en el trabajo, los empleados est\u00e1n mucho m\u00e1s relajados, porque disponen de m\u00e1s tiempo para atender a otros aspectos de su vida.<\/li>\n\n\n\n<li><strong>Incrementa la autoestima<\/strong>. El tiempo es un bien valioso que no tiene precio, y carecer de \u00e9l provoca la sensaci\u00f3n de no tener control sobre la vida de uno mismo. Por el contrario, si le damos a una persona un mayor control sobre su tiempo, su autoestima sube.<\/li>\n\n\n\n<li><strong>Mejora la imagen de la empresa como empleadora<\/strong>. Logrando que resulte m\u00e1s atractiva para aquellas personas talentosas que est\u00e1n buscando trabajo.<\/li>\n\n\n\n<li><strong>Aumenta la motivaci\u00f3n y la productividad<\/strong>. La jornada intensiva da lugar a empleados m\u00e1s relajados y felices, lo cual influye positivamente tanto en su motivaci\u00f3n como en su&nbsp;<a href=\"https:\/\/www.epe.es\/es\/activos\/empleo\/20220801\/jornada-laboral-intensiva-tiempo-rendimiento-14203429\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">nivel de productividad<\/a>.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Inconvenientes<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Hay sectores en los que no se puede aplicar<\/strong>. Por mucho que se quiera implantar, hay sectores como el comercio o la hosteler\u00eda en los que esta forma de trabajar es totalmente inviable.<\/li>\n\n\n\n<li><strong>Incompatibilidad horaria<\/strong>. En algunos casos, el cambio de horario de la empresa puede convertirse en un problema para sus clientes y\/o proveedores.<\/li>\n\n\n\n<li><strong>Aumento del estr\u00e9s<\/strong>. Si el cambio de jornada no va unido a una mejor redistribuci\u00f3n de las tareas y una mejor gesti\u00f3n del tiempo de trabajo, los niveles de estr\u00e9s en algunos empleados pueden ascender.<\/li>\n<\/ul>\n\n\n\n<p>Aunque hay algunos inconvenientes, lo cierto es que, en la mayor\u00eda de los casos, con la jornada intensiva salen ganando tanto la empresa como sus trabajadores. Es por ello que cada vez m\u00e1s negocios est\u00e1n abordando esta forma de trabajar y comprobando de forma directa todos sus beneficios.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La jornada intensiva es un tipo de jornada especialmente atractiva para los trabajadores, porque les permite aprovechar mejor su tiempo y conciliar su vida personal y profesional. <\/p>\n","protected":false},"author":20,"featured_media":27466,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[288],"tags":[311],"class_list":["post-27541","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-control-horario","tag-control-horario","no-featured-image-padding"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.stelorder.com\/fr\/wp-json\/wp\/v2\/posts\/27541","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.stelorder.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.stelorder.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.stelorder.com\/fr\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/www.stelorder.com\/fr\/wp-json\/wp\/v2\/comments?post=27541"}],"version-history":[{"count":0,"href":"https:\/\/www.stelorder.com\/fr\/wp-json\/wp\/v2\/posts\/27541\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.stelorder.com\/fr\/wp-json\/wp\/v2\/media\/27466"}],"wp:attachment":[{"href":"https:\/\/www.stelorder.com\/fr\/wp-json\/wp\/v2\/media?parent=27541"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.stelorder.com\/fr\/wp-json\/wp\/v2\/categories?post=27541"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.stelorder.com\/fr\/wp-json\/wp\/v2\/tags?post=27541"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}